{"id":166,"count":2,"description":"","link":"https:\/\/www.atelierstimamiglio.com\/en\/category\/originfair-en\/","name":"originfair","slug":"originfair-en","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>originfair Archivi - Atelier Stimamiglio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.atelierstimamiglio.com\/category\/originfair\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"originfair Archivi - Atelier Stimamiglio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.atelierstimamiglio.com\/category\/originfair\/\" \/>\n<meta property=\"og:site_name\" content=\"Atelier Stimamiglio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.atelierstimamiglio.com\/category\/originfair\/\",\"url\":\"https:\/\/www.atelierstimamiglio.com\/category\/originfair\/\",\"name\":\"originfair Archivi - Atelier Stimamiglio\",\"isPartOf\":{\"@id\":\"https:\/\/www.atelierstimamiglio.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.atelierstimamiglio.com\/category\/originfair\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.atelierstimamiglio.com\/category\/originfair\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.atelierstimamiglio.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"originfair\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.atelierstimamiglio.com\/#website\",\"url\":\"https:\/\/www.atelierstimamiglio.com\/\",\"name\":\"Atelier Stimamiglio\",\"description\":\"Affianca maison e stilisti, italiani e internazionali,\\u0003nella manifattura e nell\u2019industrializzazione di collezioni e capi pret-\u00e0-porter e pret-\u00e0-couture\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.atelierstimamiglio.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"originfair Archivi - Atelier Stimamiglio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.atelierstimamiglio.com\/category\/originfair\/","og_locale":"en_US","og_type":"article","og_title":"originfair Archivi - Atelier Stimamiglio","og_url":"https:\/\/www.atelierstimamiglio.com\/category\/originfair\/","og_site_name":"Atelier Stimamiglio","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.atelierstimamiglio.com\/category\/originfair\/","url":"https:\/\/www.atelierstimamiglio.com\/category\/originfair\/","name":"originfair Archivi - Atelier Stimamiglio","isPartOf":{"@id":"https:\/\/www.atelierstimamiglio.com\/#website"},"breadcrumb":{"@id":"https:\/\/www.atelierstimamiglio.com\/category\/originfair\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.atelierstimamiglio.com\/category\/originfair\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.atelierstimamiglio.com\/en\/"},{"@type":"ListItem","position":2,"name":"originfair"}]},{"@type":"WebSite","@id":"https:\/\/www.atelierstimamiglio.com\/#website","url":"https:\/\/www.atelierstimamiglio.com\/","name":"Atelier Stimamiglio","description":"Affianca maison e stilisti, italiani e internazionali,\u0003nella manifattura e nell\u2019industrializzazione di collezioni e capi pret-\u00e0-porter e pret-\u00e0-couture","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.atelierstimamiglio.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.atelierstimamiglio.com\/en\/wp-json\/wp\/v2\/categories\/166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.atelierstimamiglio.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.atelierstimamiglio.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.atelierstimamiglio.com\/en\/wp-json\/wp\/v2\/posts?categories=166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}